{"id":1038,"date":"2021-09-01T13:49:53","date_gmt":"2021-09-01T13:49:53","guid":{"rendered":"http:\/\/dummy.xtemos.com\/woodmart2\/elementor\/?page_id=1038"},"modified":"2026-03-01T16:49:38","modified_gmt":"2026-03-01T16:49:38","slug":"home","status":"publish","type":"page","link":"https:\/\/alsafwacarpets.store\/en\/","title":{"rendered":"Home"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1038\" class=\"elementor elementor-1038\">\n\t\t\t\t<div class=\"wd-negative-gap elementor-element elementor-element-f4ce794 wd-section-stretch e-flex e-con-boxed e-con e-parent\" data-id=\"f4ce794\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;,&quot;background_video_link&quot;:&quot;\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/\\u0631\\u0645\\u0636\\u0627\\u0646-\\u064a\\u0642\\u062a\\u0631\\u0628-\\u0623\\u062c\\u0648\\u0627\\u0621-\\u0647\\u0627\\u062f\\u0626\\u0629\\u060c-\\u062f\\u0641\\u0621-\\u0641\\u064a-\\u0627\\u0644\\u062a\\u0641\\u0627\\u0635\\u064a\\u0644\\u060c-\\u0648\\u0644\\u0645\\u0633\\u0629-\\u0641\\u062e\\u0627\\u0645\\u0629-\\u062a\\u0643\\u0645\\u0651\\u0644-\\u062c\\u0645\\u0627\\u0644-\\u0645\\u0646\\u0632\\u0644\\u0643-\\u0641\\u064a-\\u0647\\u0630\\u0627-\\u0627\\u0644\\u0634\\u0647\\u0631-\\u0627\\u0644\\u0645\\u0628\\u0627\\u0631\\u0643.\\u0627\\u0633\\u062a\\u0639.mp4&quot;,&quot;background_play_on_mobile&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-background-video-container\">\n\t\t\t\t\t\t\t<video class=\"elementor-background-video-hosted\" role=\"presentation\" autoplay muted playsinline loop><\/video>\n\t\t\t\t\t<\/div>\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-4ba9a17 e-flex e-con-boxed e-con e-parent\" data-id=\"4ba9a17\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7ed35f2 elementor-widget elementor-widget-spacer\" data-id=\"7ed35f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-7d69783 e-flex e-con-boxed e-con e-parent\" data-id=\"7d69783\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-50d717f wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"50d717f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper wd-set-mb reset-last-child wd-title-color-default wd-title-style-default wd-title-size-large text-center\">\n\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"title-subtitle subtitle-color-default subtitle-style-default wd-fontsize-xs\">\n\t\t\t\t\tTHE ART OF ANATOLIA\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title wd-fontsize-xxl\">Exquisite Turkish Masterpieces<\/h4> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"title-after_title reset-last-child wd-fontsize-s\">\n\t\t\t\t\t<p>Discover a world where tradition meets luxury. Our Turkish collection features hand-selected designs ranging from intricate silk classics to minimalist modern styles, crafted to bring warmth and prestige to your home.<\/p>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-364b0d7 wd-width-100 elementor-widget elementor-widget-wd_products\" data-id=\"364b0d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_products.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"wd-products-element\">\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"products wd-products grid-columns-4 elements-grid wd-grid-g\" data-paged=\"1\" data-atts=\"{&quot;speed&quot;:null,&quot;slides_per_view&quot;:null,&quot;wrap&quot;:null,&quot;autoplay&quot;:null,&quot;autoheight&quot;:null,&quot;hide_pagination_control&quot;:null,&quot;dynamic_pagination_control&quot;:null,&quot;hide_prev_next_buttons&quot;:null,&quot;carousel_arrows_position&quot;:null,&quot;hide_scrollbar&quot;:null,&quot;scroll_per_page&quot;:null,&quot;center_mode&quot;:null,&quot;spacing&quot;:&quot;&quot;,&quot;carousel_sync&quot;:null,&quot;sync_parent_id&quot;:null,&quot;sync_child_id&quot;:null,&quot;scroll_carousel_init&quot;:null,&quot;disable_overflow_carousel&quot;:null,&quot;include&quot;:null,&quot;meta_key&quot;:null,&quot;shop_tools&quot;:null,&quot;ajax_recently_viewed&quot;:null,&quot;pagination_arrows_position&quot;:null,&quot;items_per_page&quot;:8,&quot;columns&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]},&quot;products_masonry&quot;:&quot;&quot;,&quot;products_different_sizes&quot;:&quot;&quot;,&quot;product_quantity&quot;:&quot;&quot;,&quot;sale_countdown&quot;:&quot;0&quot;,&quot;stretch_product&quot;:null,&quot;stock_progress_bar&quot;:&quot;0&quot;,&quot;highlighted_products&quot;:&quot;0&quot;,&quot;products_divider&quot;:null,&quot;products_bordered_grid&quot;:&quot;0&quot;,&quot;products_bordered_grid_style&quot;:null,&quot;products_with_background&quot;:&quot;0&quot;,&quot;products_shadow&quot;:&quot;0&quot;,&quot;img_size&quot;:&quot;large&quot;,&quot;img_size_custom&quot;:null,&quot;grid_gallery_control&quot;:null,&quot;grid_gallery_enable_arrows&quot;:null,&quot;elementor&quot;:true,&quot;force_not_ajax&quot;:&quot;no&quot;}\" data-source=\"shortcode\" data-columns=\"4\" data-grid-gallery=\"\" style=\"--wd-col-lg:4;--wd-col-md:4;--wd-col-sm:2;--wd-gap-lg:20px;--wd-gap-sm:10px;\">\n\t\t\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-icons wd-col product-grid-item product type-product post-372 status-publish instock product_cat-turkish-carpets has-post-thumbnail shipping-taxable purchasable product-type-variable\" data-loop=\"1\" data-id=\"372\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-1\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Product 1\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-955450-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-955450-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-955450-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-955450-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-955450-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-955450-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-955450-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-955450.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4748343-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4748343-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4748343-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4748343-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4748343-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4748343-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4748343-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4748343.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-1\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_372\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"372\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Product 1&rdquo;\" rel=\"nofollow\"><span>Select options<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_372\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/alsafwacarpets.store\/en\/product\/product-1\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"372\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/compare\/\" data-id=\"372\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/alsafwacarpets.store\/en\/wishlist\/\" data-key=\"6105eeffa5\" data-product-id=\"372\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-1\/\">Product 1<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product-category\/turkish-carpets\/\" rel=\"tag\">Turkish Carpets<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x62f;.&#x625;<\/span>&nbsp;550.00<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-icons wd-col product-grid-item product type-product post-29051 status-publish instock product_cat-by-size has-post-thumbnail shipping-taxable purchasable product-type-variable\" data-loop=\"2\" data-id=\"29051\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-2\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Product 2\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-1116933-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-1116933-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-1116933-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-1116933-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-1116933-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-1116933-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-1116933-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-1116933.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2657772-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2657772-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2657772-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2657772-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2657772-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2657772-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2657772-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2657772.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-2\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_29051\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"29051\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Product 2&rdquo;\" rel=\"nofollow\"><span>Select options<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_29051\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/alsafwacarpets.store\/en\/product\/product-2\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"29051\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/compare\/\" data-id=\"29051\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/alsafwacarpets.store\/en\/wishlist\/\" data-key=\"6105eeffa5\" data-product-id=\"29051\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-2\/\">Product 2<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product-category\/by-size\/\" rel=\"tag\">By Size<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x62f;.&#x625;<\/span>&nbsp;179.99<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-icons wd-col product-grid-item product type-product post-29056 status-publish last instock product_cat-by-style has-post-thumbnail shipping-taxable purchasable product-type-variable\" data-loop=\"3\" data-id=\"29056\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-3\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Product 3\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2508117-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2508117-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2508117-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2508117-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2508117-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2508117-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2508117-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2508117.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2368621-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2368621-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2368621-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2368621-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2368621-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2368621-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2368621-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2368621.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-3\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_29056\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"29056\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Product 3&rdquo;\" rel=\"nofollow\"><span>Select options<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_29056\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/alsafwacarpets.store\/en\/product\/product-3\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"29056\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/compare\/\" data-id=\"29056\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/alsafwacarpets.store\/en\/wishlist\/\" data-key=\"6105eeffa5\" data-product-id=\"29056\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-3\/\">Product 3<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product-category\/by-style\/\" rel=\"tag\">By Style<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x62f;.&#x625;<\/span>&nbsp;179.99<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-icons wd-col product-grid-item product type-product post-29065 status-publish first instock product_cat-iranian-carpets product_cat-luxurious-classic has-post-thumbnail shipping-taxable purchasable product-type-variable\" data-loop=\"4\" data-id=\"29065\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-4\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Product 4\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2853381-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2853381-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2853381-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2853381-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2853381-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2853381-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2853381-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2853381.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3245991-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3245991-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3245991-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3245991-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3245991-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3245991-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3245991-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3245991.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-4\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_29065\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"29065\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Product 4&rdquo;\" rel=\"nofollow\"><span>Select options<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_29065\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/alsafwacarpets.store\/en\/product\/product-4\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"29065\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/compare\/\" data-id=\"29065\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/alsafwacarpets.store\/en\/wishlist\/\" data-key=\"6105eeffa5\" data-product-id=\"29065\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-4\/\">Product 4<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product-category\/iranian-carpets\/\" rel=\"tag\">Iranian Carpets<\/a>, <a href=\"https:\/\/alsafwacarpets.store\/en\/product-category\/iranian-carpets\/luxurious-classic\/\" rel=\"tag\">Luxurious Classic<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x62f;.&#x625;<\/span>&nbsp;179.99<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-icons wd-col product-grid-item product type-product post-29073 status-publish instock product_cat-offers-and-packages has-post-thumbnail shipping-taxable purchasable product-type-variable\" data-loop=\"5\" data-id=\"29073\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-5\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Product 5\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3394939-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3394939-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3394939-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3394939-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3394939-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3394939-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3394939-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3394939.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2428162-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2428162-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2428162-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2428162-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2428162-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2428162-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2428162-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2428162.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-5\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_29073\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"29073\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Product 5&rdquo;\" rel=\"nofollow\"><span>Select options<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_29073\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/alsafwacarpets.store\/en\/product\/product-5\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"29073\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/compare\/\" data-id=\"29073\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/alsafwacarpets.store\/en\/wishlist\/\" data-key=\"6105eeffa5\" data-product-id=\"29073\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-5\/\">Product 5<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product-category\/offers-and-packages\/\" rel=\"tag\">Offers and Packages<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x62f;.&#x625;<\/span>&nbsp;179.99<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-icons wd-col product-grid-item product type-product post-29081 status-publish instock product_cat-iranian-carpets has-post-thumbnail shipping-taxable purchasable product-type-variable\" data-loop=\"6\" data-id=\"29081\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-6\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Product 6\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6531337-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6531337-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6531337-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6531337-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6531337-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6531337-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6531337-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6531337.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-272355-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-272355-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-272355-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-272355-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-272355-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-272355-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-272355-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-272355.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-6\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_29081\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"29081\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Product 6&rdquo;\" rel=\"nofollow\"><span>Select options<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_29081\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/alsafwacarpets.store\/en\/product\/product-6\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"29081\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/compare\/\" data-id=\"29081\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/alsafwacarpets.store\/en\/wishlist\/\" data-key=\"6105eeffa5\" data-product-id=\"29081\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-6\/\">Product 6<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product-category\/iranian-carpets\/\" rel=\"tag\">Iranian Carpets<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x62f;.&#x625;<\/span>&nbsp;179.99<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-icons wd-col product-grid-item product type-product post-29089 status-publish last instock product_cat-home-gifts has-post-thumbnail shipping-taxable purchasable product-type-variable\" data-loop=\"7\" data-id=\"29089\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-7\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Product 7\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4351965-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4351965-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4351965-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4351965-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4351965-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4351965-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4351965-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4351965.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6153752-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6153752-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6153752-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6153752-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6153752-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6153752-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6153752-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6153752.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-7\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_29089\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"29089\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Product 7&rdquo;\" rel=\"nofollow\"><span>Select options<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_29089\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/alsafwacarpets.store\/en\/product\/product-7\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"29089\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/compare\/\" data-id=\"29089\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/alsafwacarpets.store\/en\/wishlist\/\" data-key=\"6105eeffa5\" data-product-id=\"29089\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-7\/\">Product 7<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product-category\/home-gifts\/\" rel=\"tag\">Home Gifts<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x62f;.&#x625;<\/span>&nbsp;179.99<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-icons wd-col product-grid-item product type-product post-29098 status-publish first instock product_cat-offers-and-packages has-post-thumbnail shipping-taxable purchasable product-type-variable\" data-loop=\"8\" data-id=\"29098\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-8\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Product 8\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-8374965-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-8374965-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-8374965-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-8374965-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-8374965-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-8374965-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-8374965-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-8374965.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3794560-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3794560-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3794560-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3794560-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3794560-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3794560-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3794560-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3794560.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-8\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_29098\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"29098\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Product 8&rdquo;\" rel=\"nofollow\"><span>Select options<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_29098\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/alsafwacarpets.store\/en\/product\/product-8\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"29098\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/compare\/\" data-id=\"29098\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/alsafwacarpets.store\/en\/wishlist\/\" data-key=\"6105eeffa5\" data-product-id=\"29098\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-8\/\">Product 8<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product-category\/offers-and-packages\/\" rel=\"tag\">Offers and Packages<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x62f;.&#x625;<\/span>&nbsp;179.99<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\n\t\t\t\t<\/div>\n\t\n\t\t\n\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f287800 elementor-widget elementor-widget-wd_button\" data-id=\"f287800\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-button-wrapper text-center\" >\n\t\t\t<a class=\"btn btn-style-default btn-shape-rectangle btn-size-default btn-color-primary btn-icon-pos-right\"  href=\"\/product-category\/turkish-carpets\/\">\n\t\t\t\t<span class=\"wd-btn-text\" data-elementor-setting-key=\"text\">\n\t\t\t\t\tVIEW ALL\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-ebf98e3 e-flex e-con-boxed e-con e-parent\" data-id=\"ebf98e3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-704c6c8 elementor-widget elementor-widget-spacer\" data-id=\"704c6c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-63c09eb e-flex e-con-boxed e-con e-parent\" data-id=\"63c09eb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3d8bd0e wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"3d8bd0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper wd-set-mb reset-last-child wd-title-color-default wd-title-style-default wd-title-size-large text-center\">\n\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"title-subtitle subtitle-color-default subtitle-style-default wd-fontsize-xs\">\n\t\t\t\t\tLIMITED TIME OFFERS\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title wd-fontsize-xxl\">Unmissable Seasonal Deals<\/h4> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"title-after_title reset-last-child wd-fontsize-s\">\n\t\t\t\t\tHigh-end quality meets exceptional value. Explore our latest discounts on Turkish and Iranian collections, including our popular clearance sets and cleaning packages.\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e0f9f6 wd-width-100 elementor-widget elementor-widget-wd_products\" data-id=\"8e0f9f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_products.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"wd-products-element\">\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"products wd-products grid-columns-4 elements-grid wd-grid-g\" data-paged=\"1\" data-atts=\"{&quot;speed&quot;:null,&quot;slides_per_view&quot;:null,&quot;wrap&quot;:null,&quot;autoplay&quot;:null,&quot;autoheight&quot;:null,&quot;hide_pagination_control&quot;:null,&quot;dynamic_pagination_control&quot;:null,&quot;hide_prev_next_buttons&quot;:null,&quot;carousel_arrows_position&quot;:null,&quot;hide_scrollbar&quot;:null,&quot;scroll_per_page&quot;:null,&quot;center_mode&quot;:null,&quot;spacing&quot;:&quot;&quot;,&quot;carousel_sync&quot;:null,&quot;sync_parent_id&quot;:null,&quot;sync_child_id&quot;:null,&quot;scroll_carousel_init&quot;:null,&quot;disable_overflow_carousel&quot;:null,&quot;include&quot;:null,&quot;meta_key&quot;:null,&quot;shop_tools&quot;:null,&quot;ajax_recently_viewed&quot;:null,&quot;pagination_arrows_position&quot;:null,&quot;items_per_page&quot;:8,&quot;columns&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]},&quot;products_masonry&quot;:&quot;&quot;,&quot;products_different_sizes&quot;:&quot;&quot;,&quot;product_quantity&quot;:&quot;&quot;,&quot;sale_countdown&quot;:&quot;0&quot;,&quot;stretch_product&quot;:null,&quot;stock_progress_bar&quot;:&quot;0&quot;,&quot;highlighted_products&quot;:&quot;0&quot;,&quot;products_divider&quot;:null,&quot;products_bordered_grid&quot;:&quot;0&quot;,&quot;products_bordered_grid_style&quot;:null,&quot;products_with_background&quot;:&quot;0&quot;,&quot;products_shadow&quot;:&quot;0&quot;,&quot;img_size&quot;:&quot;large&quot;,&quot;img_size_custom&quot;:null,&quot;grid_gallery_control&quot;:null,&quot;grid_gallery_enable_arrows&quot;:null,&quot;elementor&quot;:true,&quot;force_not_ajax&quot;:&quot;no&quot;}\" data-source=\"shortcode\" data-columns=\"4\" data-grid-gallery=\"\" style=\"--wd-col-lg:4;--wd-col-md:4;--wd-col-sm:2;--wd-gap-lg:20px;--wd-gap-sm:10px;\">\n\t\t\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-icons wd-col product-grid-item product type-product post-372 status-publish instock product_cat-turkish-carpets has-post-thumbnail shipping-taxable purchasable product-type-variable\" data-loop=\"1\" data-id=\"372\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-1\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Product 1\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-955450-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-955450-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-955450-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-955450-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-955450-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-955450-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-955450-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-955450.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4748343-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4748343-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4748343-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4748343-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4748343-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4748343-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4748343-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4748343.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-1\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_372\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"372\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Product 1&rdquo;\" rel=\"nofollow\"><span>Select options<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_372\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/alsafwacarpets.store\/en\/product\/product-1\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"372\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/compare\/\" data-id=\"372\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/alsafwacarpets.store\/en\/wishlist\/\" data-key=\"6105eeffa5\" data-product-id=\"372\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-1\/\">Product 1<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product-category\/turkish-carpets\/\" rel=\"tag\">Turkish Carpets<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x62f;.&#x625;<\/span>&nbsp;550.00<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-icons wd-col product-grid-item product type-product post-29051 status-publish instock product_cat-by-size has-post-thumbnail shipping-taxable purchasable product-type-variable\" data-loop=\"2\" data-id=\"29051\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-2\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Product 2\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-1116933-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-1116933-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-1116933-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-1116933-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-1116933-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-1116933-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-1116933-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-1116933.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2657772-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2657772-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2657772-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2657772-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2657772-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2657772-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2657772-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2657772.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-2\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_29051\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"29051\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Product 2&rdquo;\" rel=\"nofollow\"><span>Select options<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_29051\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/alsafwacarpets.store\/en\/product\/product-2\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"29051\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/compare\/\" data-id=\"29051\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/alsafwacarpets.store\/en\/wishlist\/\" data-key=\"6105eeffa5\" data-product-id=\"29051\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-2\/\">Product 2<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product-category\/by-size\/\" rel=\"tag\">By Size<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x62f;.&#x625;<\/span>&nbsp;179.99<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-icons wd-col product-grid-item product type-product post-29056 status-publish last instock product_cat-by-style has-post-thumbnail shipping-taxable purchasable product-type-variable\" data-loop=\"3\" data-id=\"29056\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-3\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Product 3\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2508117-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2508117-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2508117-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2508117-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2508117-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2508117-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2508117-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2508117.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2368621-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2368621-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2368621-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2368621-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2368621-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2368621-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2368621-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2368621.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-3\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_29056\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"29056\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Product 3&rdquo;\" rel=\"nofollow\"><span>Select options<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_29056\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/alsafwacarpets.store\/en\/product\/product-3\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"29056\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/compare\/\" data-id=\"29056\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/alsafwacarpets.store\/en\/wishlist\/\" data-key=\"6105eeffa5\" data-product-id=\"29056\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-3\/\">Product 3<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product-category\/by-style\/\" rel=\"tag\">By Style<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x62f;.&#x625;<\/span>&nbsp;179.99<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-icons wd-col product-grid-item product type-product post-29065 status-publish first instock product_cat-iranian-carpets product_cat-luxurious-classic has-post-thumbnail shipping-taxable purchasable product-type-variable\" data-loop=\"4\" data-id=\"29065\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-4\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Product 4\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2853381-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2853381-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2853381-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2853381-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2853381-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2853381-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2853381-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2853381.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3245991-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3245991-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3245991-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3245991-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3245991-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3245991-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3245991-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3245991.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-4\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_29065\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"29065\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Product 4&rdquo;\" rel=\"nofollow\"><span>Select options<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_29065\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/alsafwacarpets.store\/en\/product\/product-4\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"29065\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/compare\/\" data-id=\"29065\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/alsafwacarpets.store\/en\/wishlist\/\" data-key=\"6105eeffa5\" data-product-id=\"29065\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-4\/\">Product 4<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product-category\/iranian-carpets\/\" rel=\"tag\">Iranian Carpets<\/a>, <a href=\"https:\/\/alsafwacarpets.store\/en\/product-category\/iranian-carpets\/luxurious-classic\/\" rel=\"tag\">Luxurious Classic<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x62f;.&#x625;<\/span>&nbsp;179.99<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-icons wd-col product-grid-item product type-product post-29073 status-publish instock product_cat-offers-and-packages has-post-thumbnail shipping-taxable purchasable product-type-variable\" data-loop=\"5\" data-id=\"29073\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-5\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Product 5\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3394939-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3394939-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3394939-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3394939-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3394939-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3394939-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3394939-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3394939.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2428162-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2428162-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2428162-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2428162-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2428162-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2428162-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2428162-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2428162.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-5\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_29073\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"29073\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Product 5&rdquo;\" rel=\"nofollow\"><span>Select options<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_29073\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/alsafwacarpets.store\/en\/product\/product-5\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"29073\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/compare\/\" data-id=\"29073\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/alsafwacarpets.store\/en\/wishlist\/\" data-key=\"6105eeffa5\" data-product-id=\"29073\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-5\/\">Product 5<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product-category\/offers-and-packages\/\" rel=\"tag\">Offers and Packages<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x62f;.&#x625;<\/span>&nbsp;179.99<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-icons wd-col product-grid-item product type-product post-29081 status-publish instock product_cat-iranian-carpets has-post-thumbnail shipping-taxable purchasable product-type-variable\" data-loop=\"6\" data-id=\"29081\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-6\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Product 6\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6531337-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6531337-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6531337-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6531337-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6531337-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6531337-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6531337-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6531337.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-272355-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-272355-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-272355-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-272355-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-272355-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-272355-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-272355-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-272355.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-6\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_29081\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"29081\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Product 6&rdquo;\" rel=\"nofollow\"><span>Select options<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_29081\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/alsafwacarpets.store\/en\/product\/product-6\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"29081\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/compare\/\" data-id=\"29081\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/alsafwacarpets.store\/en\/wishlist\/\" data-key=\"6105eeffa5\" data-product-id=\"29081\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-6\/\">Product 6<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product-category\/iranian-carpets\/\" rel=\"tag\">Iranian Carpets<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x62f;.&#x625;<\/span>&nbsp;179.99<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-icons wd-col product-grid-item product type-product post-29089 status-publish last instock product_cat-home-gifts has-post-thumbnail shipping-taxable purchasable product-type-variable\" data-loop=\"7\" data-id=\"29089\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-7\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Product 7\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4351965-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4351965-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4351965-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4351965-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4351965-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4351965-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4351965-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4351965.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6153752-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6153752-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6153752-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6153752-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6153752-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6153752-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6153752-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6153752.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-7\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_29089\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"29089\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Product 7&rdquo;\" rel=\"nofollow\"><span>Select options<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_29089\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/alsafwacarpets.store\/en\/product\/product-7\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"29089\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/compare\/\" data-id=\"29089\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/alsafwacarpets.store\/en\/wishlist\/\" data-key=\"6105eeffa5\" data-product-id=\"29089\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-7\/\">Product 7<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product-category\/home-gifts\/\" rel=\"tag\">Home Gifts<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x62f;.&#x625;<\/span>&nbsp;179.99<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-icons wd-col product-grid-item product type-product post-29098 status-publish first instock product_cat-offers-and-packages has-post-thumbnail shipping-taxable purchasable product-type-variable\" data-loop=\"8\" data-id=\"29098\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-8\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Product 8\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-8374965-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-8374965-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-8374965-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-8374965-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-8374965-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-8374965-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-8374965-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-8374965.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3794560-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3794560-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3794560-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3794560-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3794560-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3794560-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3794560-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3794560.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-8\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_29098\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"29098\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Product 8&rdquo;\" rel=\"nofollow\"><span>Select options<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_29098\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/alsafwacarpets.store\/en\/product\/product-8\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"29098\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/compare\/\" data-id=\"29098\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/alsafwacarpets.store\/en\/wishlist\/\" data-key=\"6105eeffa5\" data-product-id=\"29098\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-8\/\">Product 8<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product-category\/offers-and-packages\/\" rel=\"tag\">Offers and Packages<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x62f;.&#x625;<\/span>&nbsp;179.99<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\n\t\t\t\t<\/div>\n\t\n\t\t\n\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-526ddec elementor-widget elementor-widget-wd_button\" data-id=\"526ddec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-button-wrapper text-center\" >\n\t\t\t<a class=\"btn btn-style-default btn-shape-rectangle btn-size-default btn-color-primary btn-icon-pos-right\"  href=\"\/product-category\/offers-and-packages\/\">\n\t\t\t\t<span class=\"wd-btn-text\" data-elementor-setting-key=\"text\">\n\t\t\t\t\tVIEW ALL\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-5a9cac4 e-flex e-con-boxed e-con e-parent\" data-id=\"5a9cac4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-df59ec5 elementor-widget elementor-widget-spacer\" data-id=\"df59ec5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-9dc826b e-flex e-con-boxed e-con e-parent\" data-id=\"9dc826b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7374ed6 wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"7374ed6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper wd-set-mb reset-last-child wd-title-color-default wd-title-style-default wd-title-size-large text-center\">\n\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"title-subtitle subtitle-color-default subtitle-style-default wd-fontsize-xs\">\n\t\t\t\t\tPRESERVE THE BEAUTY\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title wd-fontsize-xxl\">Expert Carpet Care &amp; Maintenance<\/h4> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"title-after_title reset-last-child wd-fontsize-s\">\n\t\t\t\t\t<p>Keep your luxury Turkish and Iranian carpets in pristine condition. Our professional-grade shampoos, stain removers, and sanitizers are specially formulated to protect delicate fibers while ensuring a deep, lasting clean.<\/p>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bfcf33d wd-width-100 elementor-widget elementor-widget-wd_products\" data-id=\"bfcf33d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_products.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"wd-products-element\">\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"products wd-products grid-columns-4 elements-grid wd-grid-g\" data-paged=\"1\" data-atts=\"{&quot;speed&quot;:null,&quot;slides_per_view&quot;:null,&quot;wrap&quot;:null,&quot;autoplay&quot;:null,&quot;autoheight&quot;:null,&quot;hide_pagination_control&quot;:null,&quot;dynamic_pagination_control&quot;:null,&quot;hide_prev_next_buttons&quot;:null,&quot;carousel_arrows_position&quot;:null,&quot;hide_scrollbar&quot;:null,&quot;scroll_per_page&quot;:null,&quot;center_mode&quot;:null,&quot;spacing&quot;:&quot;&quot;,&quot;carousel_sync&quot;:null,&quot;sync_parent_id&quot;:null,&quot;sync_child_id&quot;:null,&quot;scroll_carousel_init&quot;:null,&quot;disable_overflow_carousel&quot;:null,&quot;include&quot;:null,&quot;meta_key&quot;:null,&quot;shop_tools&quot;:null,&quot;ajax_recently_viewed&quot;:null,&quot;pagination_arrows_position&quot;:null,&quot;items_per_page&quot;:8,&quot;columns&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]},&quot;products_masonry&quot;:&quot;&quot;,&quot;products_different_sizes&quot;:&quot;&quot;,&quot;product_quantity&quot;:&quot;&quot;,&quot;sale_countdown&quot;:&quot;0&quot;,&quot;stretch_product&quot;:null,&quot;stock_progress_bar&quot;:&quot;0&quot;,&quot;highlighted_products&quot;:&quot;0&quot;,&quot;products_divider&quot;:null,&quot;products_bordered_grid&quot;:&quot;0&quot;,&quot;products_bordered_grid_style&quot;:null,&quot;products_with_background&quot;:&quot;0&quot;,&quot;products_shadow&quot;:&quot;0&quot;,&quot;img_size&quot;:&quot;large&quot;,&quot;img_size_custom&quot;:null,&quot;grid_gallery_control&quot;:null,&quot;grid_gallery_enable_arrows&quot;:null,&quot;elementor&quot;:true,&quot;force_not_ajax&quot;:&quot;no&quot;}\" data-source=\"shortcode\" data-columns=\"4\" data-grid-gallery=\"\" style=\"--wd-col-lg:4;--wd-col-md:4;--wd-col-sm:2;--wd-gap-lg:20px;--wd-gap-sm:10px;\">\n\t\t\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-icons wd-col product-grid-item product type-product post-372 status-publish instock product_cat-turkish-carpets has-post-thumbnail shipping-taxable purchasable product-type-variable\" data-loop=\"1\" data-id=\"372\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-1\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Product 1\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-955450-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-955450-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-955450-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-955450-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-955450-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-955450-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-955450-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-955450.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4748343-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4748343-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4748343-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4748343-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4748343-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4748343-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4748343-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4748343.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-1\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_372\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"372\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Product 1&rdquo;\" rel=\"nofollow\"><span>Select options<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_372\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/alsafwacarpets.store\/en\/product\/product-1\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"372\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/compare\/\" data-id=\"372\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/alsafwacarpets.store\/en\/wishlist\/\" data-key=\"6105eeffa5\" data-product-id=\"372\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-1\/\">Product 1<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product-category\/turkish-carpets\/\" rel=\"tag\">Turkish Carpets<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x62f;.&#x625;<\/span>&nbsp;550.00<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-icons wd-col product-grid-item product type-product post-29051 status-publish instock product_cat-by-size has-post-thumbnail shipping-taxable purchasable product-type-variable\" data-loop=\"2\" data-id=\"29051\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-2\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Product 2\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-1116933-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-1116933-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-1116933-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-1116933-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-1116933-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-1116933-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-1116933-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-1116933.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2657772-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2657772-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2657772-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2657772-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2657772-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2657772-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2657772-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2657772.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-2\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_29051\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"29051\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Product 2&rdquo;\" rel=\"nofollow\"><span>Select options<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_29051\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/alsafwacarpets.store\/en\/product\/product-2\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"29051\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/compare\/\" data-id=\"29051\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/alsafwacarpets.store\/en\/wishlist\/\" data-key=\"6105eeffa5\" data-product-id=\"29051\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-2\/\">Product 2<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product-category\/by-size\/\" rel=\"tag\">By Size<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x62f;.&#x625;<\/span>&nbsp;179.99<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-icons wd-col product-grid-item product type-product post-29056 status-publish last instock product_cat-by-style has-post-thumbnail shipping-taxable purchasable product-type-variable\" data-loop=\"3\" data-id=\"29056\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-3\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Product 3\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2508117-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2508117-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2508117-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2508117-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2508117-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2508117-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2508117-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2508117.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2368621-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2368621-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2368621-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2368621-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2368621-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2368621-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2368621-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2368621.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-3\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_29056\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"29056\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Product 3&rdquo;\" rel=\"nofollow\"><span>Select options<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_29056\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/alsafwacarpets.store\/en\/product\/product-3\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"29056\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/compare\/\" data-id=\"29056\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/alsafwacarpets.store\/en\/wishlist\/\" data-key=\"6105eeffa5\" data-product-id=\"29056\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-3\/\">Product 3<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product-category\/by-style\/\" rel=\"tag\">By Style<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x62f;.&#x625;<\/span>&nbsp;179.99<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-icons wd-col product-grid-item product type-product post-29065 status-publish first instock product_cat-iranian-carpets product_cat-luxurious-classic has-post-thumbnail shipping-taxable purchasable product-type-variable\" data-loop=\"4\" data-id=\"29065\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-4\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Product 4\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2853381-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2853381-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2853381-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2853381-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2853381-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2853381-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2853381-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2853381.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3245991-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3245991-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3245991-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3245991-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3245991-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3245991-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3245991-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3245991.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-4\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_29065\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"29065\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Product 4&rdquo;\" rel=\"nofollow\"><span>Select options<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_29065\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/alsafwacarpets.store\/en\/product\/product-4\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"29065\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/compare\/\" data-id=\"29065\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/alsafwacarpets.store\/en\/wishlist\/\" data-key=\"6105eeffa5\" data-product-id=\"29065\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-4\/\">Product 4<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product-category\/iranian-carpets\/\" rel=\"tag\">Iranian Carpets<\/a>, <a href=\"https:\/\/alsafwacarpets.store\/en\/product-category\/iranian-carpets\/luxurious-classic\/\" rel=\"tag\">Luxurious Classic<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x62f;.&#x625;<\/span>&nbsp;179.99<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-icons wd-col product-grid-item product type-product post-29073 status-publish instock product_cat-offers-and-packages has-post-thumbnail shipping-taxable purchasable product-type-variable\" data-loop=\"5\" data-id=\"29073\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-5\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Product 5\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3394939-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3394939-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3394939-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3394939-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3394939-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3394939-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3394939-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3394939.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2428162-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2428162-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2428162-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2428162-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2428162-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2428162-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2428162-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-2428162.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-5\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_29073\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"29073\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Product 5&rdquo;\" rel=\"nofollow\"><span>Select options<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_29073\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/alsafwacarpets.store\/en\/product\/product-5\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"29073\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/compare\/\" data-id=\"29073\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/alsafwacarpets.store\/en\/wishlist\/\" data-key=\"6105eeffa5\" data-product-id=\"29073\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-5\/\">Product 5<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product-category\/offers-and-packages\/\" rel=\"tag\">Offers and Packages<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x62f;.&#x625;<\/span>&nbsp;179.99<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-icons wd-col product-grid-item product type-product post-29081 status-publish instock product_cat-iranian-carpets has-post-thumbnail shipping-taxable purchasable product-type-variable\" data-loop=\"6\" data-id=\"29081\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-6\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Product 6\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6531337-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6531337-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6531337-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6531337-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6531337-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6531337-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6531337-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6531337.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-272355-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-272355-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-272355-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-272355-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-272355-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-272355-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-272355-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-272355.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-6\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_29081\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"29081\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Product 6&rdquo;\" rel=\"nofollow\"><span>Select options<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_29081\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/alsafwacarpets.store\/en\/product\/product-6\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"29081\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/compare\/\" data-id=\"29081\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/alsafwacarpets.store\/en\/wishlist\/\" data-key=\"6105eeffa5\" data-product-id=\"29081\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-6\/\">Product 6<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product-category\/iranian-carpets\/\" rel=\"tag\">Iranian Carpets<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x62f;.&#x625;<\/span>&nbsp;179.99<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-icons wd-col product-grid-item product type-product post-29089 status-publish last instock product_cat-home-gifts has-post-thumbnail shipping-taxable purchasable product-type-variable\" data-loop=\"7\" data-id=\"29089\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-7\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Product 7\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4351965-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4351965-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4351965-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4351965-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4351965-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4351965-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4351965-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-4351965.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6153752-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6153752-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6153752-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6153752-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6153752-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6153752-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6153752-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-6153752.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-7\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_29089\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"29089\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Product 7&rdquo;\" rel=\"nofollow\"><span>Select options<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_29089\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/alsafwacarpets.store\/en\/product\/product-7\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"29089\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/compare\/\" data-id=\"29089\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/alsafwacarpets.store\/en\/wishlist\/\" data-key=\"6105eeffa5\" data-product-id=\"29089\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-7\/\">Product 7<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product-category\/home-gifts\/\" rel=\"tag\">Home Gifts<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x62f;.&#x625;<\/span>&nbsp;179.99<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-icons wd-col product-grid-item product type-product post-29098 status-publish first instock product_cat-offers-and-packages has-post-thumbnail shipping-taxable purchasable product-type-variable\" data-loop=\"8\" data-id=\"29098\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-8\/\" class=\"product-image-link\" tabindex=\"-1\" aria-label=\"Product 8\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-8374965-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-8374965-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-8374965-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-8374965-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-8374965-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-8374965-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-8374965-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-8374965.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3794560-640x800.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3794560-640x800.jpg 640w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3794560-430x538.jpg 430w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3794560-150x188.jpg 150w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3794560-700x875.jpg 700w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3794560-240x300.jpg 240w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3794560-768x960.jpg 768w, https:\/\/alsafwacarpets.store\/wp-content\/uploads\/2026\/02\/image-3794560.jpg 1080w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-8\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_29098\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"29098\" data-product_sku=\"\" aria-label=\"Select options for &ldquo;Product 8&rdquo;\" rel=\"nofollow\"><span>Select options<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_29098\" class=\"screen-reader-text\">\n\t\tThis product has multiple variants. The options may be chosen on the product page\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/alsafwacarpets.store\/en\/product\/product-8\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"29098\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/compare\/\" data-id=\"29098\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t<span class=\"wd-action-text\">Add to compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/alsafwacarpets.store\/en\/wishlist\/\" data-key=\"6105eeffa5\" data-product-id=\"29098\" rel=\"nofollow\" data-added-text=\"Browse wishlist\">\n\t\t\t\t\t<span class=\"wd-added-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/alsafwacarpets.store\/en\/product\/product-8\/\">Product 8<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/alsafwacarpets.store\/en\/product-category\/offers-and-packages\/\" rel=\"tag\">Offers and Packages<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#x62f;.&#x625;<\/span>&nbsp;179.99<\/bdi><\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\n\t\t\t\t<\/div>\n\t\n\t\t\n\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7219d9 elementor-widget elementor-widget-wd_button\" data-id=\"a7219d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-button-wrapper text-center\" >\n\t\t\t<a class=\"btn btn-style-default btn-shape-rectangle btn-size-default btn-color-primary btn-icon-pos-right\"  href=\"\/product-category\/carpet-cleaners-and-care\/\">\n\t\t\t\t<span class=\"wd-btn-text\" data-elementor-setting-key=\"text\">\n\t\t\t\t\tVIEW ALL\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>THE ART OF ANATOLIA Exquisite Turkish Masterpieces Discover a world where tradition meets luxury. Our Turkish collection features hand-selected designs<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1038","page","type-page","status-publish","hentry"],"_hostinger_reach_plugin_has_subscription_block":false,"_hostinger_reach_plugin_is_elementor":false,"_links":{"self":[{"href":"https:\/\/alsafwacarpets.store\/en\/wp-json\/wp\/v2\/pages\/1038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alsafwacarpets.store\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/alsafwacarpets.store\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/alsafwacarpets.store\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/alsafwacarpets.store\/en\/wp-json\/wp\/v2\/comments?post=1038"}],"version-history":[{"count":10,"href":"https:\/\/alsafwacarpets.store\/en\/wp-json\/wp\/v2\/pages\/1038\/revisions"}],"predecessor-version":[{"id":29267,"href":"https:\/\/alsafwacarpets.store\/en\/wp-json\/wp\/v2\/pages\/1038\/revisions\/29267"}],"wp:attachment":[{"href":"https:\/\/alsafwacarpets.store\/en\/wp-json\/wp\/v2\/media?parent=1038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}